{"id":1037,"date":"2019-05-22T13:29:25","date_gmt":"2019-05-22T12:29:25","guid":{"rendered":"https:\/\/www.smartbamboo.es\/tres-grans-touroperadors-asco-alternativa-turistica\/"},"modified":"2019-05-22T13:51:08","modified_gmt":"2019-05-22T12:51:08","slug":"tres-grans-touroperadors-asco-alternativa-turistica","status":"publish","type":"post","link":"https:\/\/www.smartbamboo.es\/es\/tres-grans-touroperadors-asco-alternativa-turistica\/","title":{"rendered":"Tres grandes touroperadores hacen promoci\u00f3n tur\u00edstica de Asc\u00f3"},"content":{"rendered":"<h3 style=\"text-align: center;\">Thomas Cook Ibersol, TUI Espa\u00f1a Costa Dorada y Jet2 ponen en valor<br \/>\nla villa como destino ecotur\u00edstico y de deportes de aventura<\/h3>\n<h3 style=\"text-align: center;\">Profesionales del sector y el actor William Miller recorren el Ebro a bordo<br \/>\nde Lo Roget y visitan el casco antiguo durante su visita a Asc\u00f3<\/h3>\n<p>&nbsp;<\/p>\n<p><strong>Asc\u00f3, 21 de mayo de 2019.<\/strong> El nombre de Asc\u00f3 ha entrado con fuerza dentro de los grandes circuitos tur\u00edsticos, de la mano de tres importantes touroperadores que han empezado a promocionar la poblaci\u00f3n como una alternativa tur\u00edstica diferente de la habitual de sol y playa. Se trata de Thomas Cook Ibersol, TUI Espa\u00f1a Costa Dorada y Jet2, cuyos responsables ven Asc\u00f3 como un singular destino ecotur\u00edstico, sostenible y de deportes de aventura.<\/p>\n<p>As\u00ed lo han puesto de manifiesto hoy miembros de estas compa\u00f1\u00edas, en el transcurso de una visita que han realizado en Asc\u00f3 para conocer en primera persona las oportunidades que ofrece el pack tur\u00edstico denominado \u2018Descubre Asc\u00f3\u2019, que incide en el mercado mayoritario de la Costa Dorada. Los representantes de los touroperadores, a los cuales se ha sumado el actor William Miller, han sido recibidos por el alcalde de Asc\u00f3, Josep Maria Buixeda, quien les ha agradecido su apuesta por el municipio asconense como una opci\u00f3n tur\u00edstica diferente, con un valor natural e hist\u00f3rico muy relevante. <a href=\"http:\/\/www.smartbamboo.es\">Bamboo<\/a> ha tenido el placer de encargarse de las tareas de Prensa y Comunicaci\u00f3n vinculadas con esta iniciativa.<\/p>\n<p>Buixeda ha resaltado que \u201choy es un d\u00eda muy especial para Asc\u00f3 porque recibimos la primera visita derivada de una iniciativa que fue aprobada por el Ayuntamiento con el objetivo de potenciar el turismo\u201d. El alcalde ha recordado que, \u201ca veces, es necesario que la gente de fuera venga a dar valor a aquello que nosotros tenemos en casa para que realmente nos lo acabemos de creer\u201d. Y as\u00ed est\u00e1 pasando, seg\u00fan ha explicado, con compa\u00f1\u00edas que trabajan en coordinaci\u00f3n con los grandes touroperadores y que han empezado a ofrecer excursiones que tienen Asc\u00f3 como destino.<\/p>\n<p>La expedici\u00f3n tur\u00edstica que ha visitado hoy Asc\u00f3 estaba integrada por una quincena de personas, entre las cuales hab\u00eda, aparte de responsables de los tres touroperadors mencionados, profesionales de varios \u00e1mbitos del sector tur\u00edstico, incluyendo el director del Club BTT Dirt Factory UK, Ian Wheeler, quien est\u00e1 especialmente interesado en mostrar Asc\u00f3 y sus alrededores a trav\u00e9s del deporte en bicicleta..<\/p>\n<p><strong>Paseo por el r\u00edo a bordo de Lo Roget<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1030 aligncenter\" src=\"https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/Llau\u0308t.jpg\" alt=\"\" width=\"920\" height=\"690\" srcset=\"https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/Llau\u0308t.jpg 2000w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/Llau\u0308t-300x225.jpg 300w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/Llau\u0308t-768x576.jpg 768w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/Llau\u0308t-1024x768.jpg 1024w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/Llau\u0308t-195x146.jpg 195w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/Llau\u0308t-50x38.jpg 50w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/Llau\u0308t-187x140.jpg 187w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/Llau\u0308t-960x720.jpg 960w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/Llau\u0308t-600x450.jpg 600w\" sizes=\"(max-width:767px) 480px, (max-width:920px) 100vw, 920px\" \/><\/p>\n<p>El itinerario del grupo ha arrancado, alrededor de las 10.30 horas, con un agradable paseo por el r\u00edo Ebro, a bordo del la\u00fad Lo Roget. M\u00e1s tarde, los miembros de la delegaci\u00f3n tur\u00edstica han recorrido en bicicleta el\u00e9ctrica las calles y plazas m\u00e1s emblem\u00e1ticas de Asc\u00f3. La visita ha sido coordinada por Mandy Lloyd, empresaria especializada en promoci\u00f3n tur\u00edstica que, por encargo del Ayuntamiento, y despu\u00e9s de adjudicarse el pliego pertinente, lidera la promoci\u00f3n del paquete \u2018Descubre Asc\u00f3\u2019 en el mercado mayoritario de la Costa Dorada. \u201cLa gente quiere experiencias diferentes, aparte de costa. Y Asc\u00f3 tiene un gran potencial como alternativa ecotur\u00edstica y de aventura\u201d, ha remarcado Lloyd.<\/p>\n<p>La misma opini\u00f3n ha expresado la responsable de Excursiones de Thomas Cook Ibersol, Sandra Liny\u00e0, quien ha subrayado que \u201clos turistas de la costa cada vez m\u00e1s desean otras experiencias, conocer rincones de Catalu\u00f1a que son muy atractivos, como es el caso de Asc\u00f3. En definitiva, un turismo m\u00e1s ecol\u00f3gico y de interior. Por eso, estamos convencidos de las posibilidades de Asc\u00f3 y queremos promocionarlas\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Apoyo del actor William Miller<\/strong><\/p>\n<p>El actor William Miller ha dicho que est\u00e1 comprometido con la promoci\u00f3n de espacios singulares de la demarcaci\u00f3n de Tarragona. \u201cMe gusta ser embajador de mi tierra. He apoyado a lugares como Espluga, Montblanc, Prades o Poblet, y ahora he querido hacer lo mismo con Asc\u00f3. Tiene un ecosistema maravilloso y veo muchas posibilidades para promover un turismo diferente\u201d, ha declarado Miller, quien combina sus apariciones en \u2018Cu\u00e9ntame\u2019 con varios proyectos, como la quinta temporada de \u2018Los 100\u2019, que se acaba de estrenar en Netflix Espa\u00f1a, y est\u00e1 pendiente de cerrar un nuevo trabajo, tambi\u00e9n para Netflix, en los Estados Unidos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1032 aligncenter\" src=\"https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/grup.jpg\" alt=\"\" width=\"920\" height=\"690\" srcset=\"https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/grup.jpg 2000w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/grup-300x225.jpg 300w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/grup-768x576.jpg 768w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/grup-1024x768.jpg 1024w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/grup-195x146.jpg 195w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/grup-50x38.jpg 50w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/grup-187x140.jpg 187w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/grup-960x720.jpg 960w, https:\/\/www.smartbamboo.es\/wp-content\/uploads\/2019\/05\/grup-600x450.jpg 600w\" sizes=\"(max-width:767px) 480px, (max-width:920px) 100vw, 920px\" \/><\/p>\n<p>El alcalde de Asc\u00f3 ha recordado que el Ayuntamiento aprob\u00f3 el paquete tur\u00edstico \u2018Descubre Asc\u00f3\u2019 con el objetivo de \u201cdar a conocer todo el patrimonio hist\u00f3rico y natural, as\u00ed como la preservaci\u00f3n de la cultura que hemos hecho toda esta legislatura, en la cual hemos puesto en valor el r\u00edo, la laguna y acabamos de restaurar nuestro emblema, el castillo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thomas Cook Ibersol, TUI Espa\u00f1a Costa Dorada y Jet2 ponen en valor la villa como destino ecotur\u00edstico y de deportes de aventura Profesionales del sector y<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":1029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[137,138,139,140,51,85,128],"_links":{"self":[{"href":"https:\/\/www.smartbamboo.es\/es\/wp-json\/wp\/v2\/posts\/1037"}],"collection":[{"href":"https:\/\/www.smartbamboo.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smartbamboo.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smartbamboo.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smartbamboo.es\/es\/wp-json\/wp\/v2\/comments?post=1037"}],"version-history":[{"count":3,"href":"https:\/\/www.smartbamboo.es\/es\/wp-json\/wp\/v2\/posts\/1037\/revisions"}],"predecessor-version":[{"id":1040,"href":"https:\/\/www.smartbamboo.es\/es\/wp-json\/wp\/v2\/posts\/1037\/revisions\/1040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smartbamboo.es\/es\/wp-json\/wp\/v2\/media\/1029"}],"wp:attachment":[{"href":"https:\/\/www.smartbamboo.es\/es\/wp-json\/wp\/v2\/media?parent=1037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smartbamboo.es\/es\/wp-json\/wp\/v2\/categories?post=1037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smartbamboo.es\/es\/wp-json\/wp\/v2\/tags?post=1037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}